{"id":238363,"date":"2025-05-15T09:50:56","date_gmt":"2025-05-15T13:50:56","guid":{"rendered":"https:\/\/nuranwireless.com\/?p=238363"},"modified":"2025-05-15T09:53:45","modified_gmt":"2025-05-15T13:53:45","slug":"technicienne-comptable-2","status":"publish","type":"post","link":"https:\/\/nuranwireless.com\/fr\/nuran-career-posts-fr\/technicienne-comptable-2\/","title":{"rendered":"Technicien(ne) Comptable"},"content":{"rendered":"<p>\u00c0 temps plein<\/p>\n<p>Statut d&#8217;employ\u00e9: Permanent<\/p>\n<p>Lieu principal d\u2019emploi\u00a0: Qu\u00e9bec, Qu\u00e9bec<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Description de l&rsquo;entreprise:<\/strong><\/p>\n<p>NuRAN est une soci\u00e9t\u00e9 de t\u00e9l\u00e9communications sp\u00e9cialis\u00e9e afin de r\u00e9pondre \u00e0 la demande croissante de couverture de r\u00e9seau sans fil dans les zones recul\u00e9es et rurales du monde entier. Avec ses solutions abordables prenant en charge les technologies 2G, 3G et 4G et son mod\u00e8le d\u2019affaires innovant de R\u00e9seau en tant que Service (NaaS), NuRAN construit, optimise et g\u00e8re l\u2019expansion de la connectivit\u00e9 rurale. La mission de NuRAN est d\u2019ouvrir une nouvelle possibilit\u00e9 pour plus d\u2019un milliard de personnes de communiquer efficacement sur de longues distances. Notre engagement, nos valeurs \u00e9thiques et ambitieuses animent l\u2019entreprise dans sa mission de connecter le monde.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Description de l&#8217;emploi: <a href=\"https:\/\/nuranwireless.com\/wp-content\/uploads\/2025\/05\/Affichage-de-poste-Technicien-comptable.pdf\">ici<\/a><\/strong><\/p>\n<span class=\"et_bloom_bottom_trigger\"><\/span>","protected":false},"excerpt":{"rendered":"<p>\u00c0 temps plein Statut d&#8217;employ\u00e9: Permanent Lieu principal d\u2019emploi\u00a0: Qu\u00e9bec, Qu\u00e9bec &nbsp; Description de l&rsquo;entreprise: NuRAN est une soci\u00e9t\u00e9 de t\u00e9l\u00e9communications sp\u00e9cialis\u00e9e afin de r\u00e9pondre \u00e0 la demande croissante de [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[97],"tags":[],"class_list":["post-238363","post","type-post","status-publish","format-standard","hentry","category-nuran-career-posts-fr"],"_links":{"self":[{"href":"https:\/\/nuranwireless.com\/fr\/wp-json\/wp\/v2\/posts\/238363","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nuranwireless.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nuranwireless.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nuranwireless.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/nuranwireless.com\/fr\/wp-json\/wp\/v2\/comments?post=238363"}],"version-history":[{"count":1,"href":"https:\/\/nuranwireless.com\/fr\/wp-json\/wp\/v2\/posts\/238363\/revisions"}],"predecessor-version":[{"id":238364,"href":"https:\/\/nuranwireless.com\/fr\/wp-json\/wp\/v2\/posts\/238363\/revisions\/238364"}],"wp:attachment":[{"href":"https:\/\/nuranwireless.com\/fr\/wp-json\/wp\/v2\/media?parent=238363"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nuranwireless.com\/fr\/wp-json\/wp\/v2\/categories?post=238363"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nuranwireless.com\/fr\/wp-json\/wp\/v2\/tags?post=238363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}